{"id":225840,"date":"2023-03-13T10:59:36","date_gmt":"2023-03-13T09:59:36","guid":{"rendered":"https:\/\/lysefjorden365.wpenginepowered.com\/lastabotn-kulturarv\/"},"modified":"2026-06-15T15:37:49","modified_gmt":"2026-06-15T13:37:49","slug":"lastabotn","status":"publish","type":"page","link":"https:\/\/lysefjorden365.com\/no\/cultural-heritage\/lastabotn\/","title":{"rendered":"Lastebotn"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_0 et_pb_row et_block_row\"><div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h1 style=\"text-align: center;\"> Lastebotn <\/h1>\n<\/div><\/div><div class=\"et_pb_divider_0 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><p><span>Gruvedrift har preget Lastabotn i omtrent 200 \u00e5r, men dessverre har den aldri v\u00e6rt spesielt l\u00f8nnsom. Til tross for dette har gruvedriften skapt liv og aktivitet i fjorden, og synlige spor etter driften kan fortsatt finnes i omr\u00e5det.<\/span><\/p>\n<\/div><\/div><div class=\"et_pb_image_0 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/02\/Lastabotn.webp\" width=\"1920\" height=\"1082\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/02\/Lastabotn.webp 1920w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/02\/Lastabotn-1280x721.webp 1280w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/02\/Lastabotn-980x552.webp 980w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/02\/Lastabotn-480x271.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1920px, 100vw\" class=\"wp-image-236411\" title=\"Lastebotn\" \/><\/span><\/div><\/div><\/div><\/div><div class=\"et_pb_section_1 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_1 et_pb_row et_pb_gutters3 et_block_row\"><div class=\"et_pb_column_1 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>Siden 1745 har Lastabotn hatt flere perioder med gruvedrift, men dessverre var det aldri s\u00e6rlig l\u00f8nnsomt. Gruveindustrien tiltrakk seg ansettelser av b\u00e5de lokale og utenlandske arbeidere, inkludert tyske og andre gruvearbeidere. \"Enighetens Kobberv\u00e6rk\" ble etablert i 1764, men etter noen \u00e5r var eierne uenige, og transport av malm til et smelteverk i Hjelmeland ble for dyrt.<\/p>\n<p>I gruveperioden var det mye aktivitet i Lastabotn. De utenlandske arbeiderne ble godt mottatt i fjorden, og noen av dem giftet seg til og med med kvinner fra omr\u00e5det. Men da gruvedriften ble nedlagt, flyttet mange videre til andre gruvesamfunn. Engelske interesser gjenopptok gruvedriften i 1868, men igjen uten hell. I 1915 pr\u00f8vde folk fra Stavanger seg p\u00e5 gruvedrift, ogs\u00e5 uten s\u00e6rlig hell.<\/p>\n<p>I dag er gruvegangene stengt, men spor etter gruvedrift er fortsatt synlige i omr\u00e5det, og fjellet b\u00e6rer preg av kobbermalm.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_2 et_pb_row et_block_row\"><div class=\"et_pb_column_2 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"dipi_image_hotspot_0 dipi_image_hotspot et_pb_bg_layout_light et_pb_module\">\n\t\t\t<div class=\"dipi-image-hotspot dipi-trigger_on_click-off\" data-order-number=\"0\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2023\/03\/Kulturarv-Lysefjorden.jpg\" class=\"dipi-hotspot-bg-image-main\" alt=\"\">\n\t\t\t\t<div class=\"dipi_image_hotspot_child_0 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"0\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Oanes og Forsand\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/oanes-og-forsand\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key634200600 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key634200600 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_1 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"1\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Bergsholmen\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/#bergsholmen\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                <a href=\"#bergsholmen\" target=\"_self\">\n                    \n                <span style=\"animation: pulse-key1261209296 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1261209296 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                <\/a>\n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_2 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"2\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                H\u00f8llesli\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/hollesli\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key1745849276 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1745849276 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_3 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"3\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Lastebotn\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/lastabotn\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key1512534620 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1512534620 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_4 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"4\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                D\u00f8rvika\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/dorvika\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key1268475250 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1268475250 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_5 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"5\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Fantahola\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/fantahola\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key1801055691 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1801055691 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_6 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"6\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Revs\u00e5\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/revsa\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key1704034798 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1704034798 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_7 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"7\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Eiane\/Fossmork\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/eiane-fossmork\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key2101789345 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key2101789345 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_8 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"8\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Vatne og Torsnes\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/vatne-og-torsnes\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key1502214353 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1502214353 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_9 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"9\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Preikestolen\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/preikestolen\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key537739204 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key537739204 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_10 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"10\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Neverdalen\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/#neverdalen\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                <a href=\"#neverdalen\" target=\"_self\">\n                    \n                <span style=\"animation: pulse-key280492111 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key280492111 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                <\/a>\n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_11 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"11\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Hengjane\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/hengjane\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key597837878 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key597837878 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_12 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"12\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Bratteli\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/bratteli\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key438248799 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key438248799 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_13 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"13\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Bakken\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/bakken\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key1743479953 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1743479953 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_14 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"14\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Mulen og Jomfru Maria\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/mulen-og-jomfru-maria\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key570835137 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key570835137 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_15 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"15\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Songesand\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/sangesand\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key628503311 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key628503311 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_16 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"16\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Kallastein og Kallali\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/kallestein-og-kallali\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key983452260 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key983452260 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_17 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"17\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Fl\u00f8rli\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/florli\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key1987371744 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1987371744 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_18 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"18\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                H\u00e5heller\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/haheller\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key1332212570 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1332212570 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_19 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"19\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Fylgjesdalen\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/fylgjesdalen\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key1557422057 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1557422057 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_20 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"20\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Kjerag\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/kjerag\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key1045521573 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key1045521573 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div><div class=\"dipi_image_hotspot_child_21 dipi_image_hotspot_child et_pb_bg_layout_light et_pb_module\">\n            <div class=\"dipi-image-hotspot-child\">\n                \n                    <div\n                        class=\"dipi-tooltip-wrap dipi-tooltip-position-right  animated fadeIn\"\n                        data-order-number=\"21\"\n                    >\n                        \n                        <h2 class=\"dipi-tooltip-title\">\n                Lysebotn\n            <\/h2>\n                        \n                        <div class=\"dipi-tooltip-button-wrap\"><a class=\"et_pb_button dipi-tooltip-button\" href=\"\/no\/kulturarv\/lysebotn\/\" data-icon=\"1\">Les mer<\/a><\/div>\n                    <\/div>\n                \n            <div class=\"dipi-hotspot\">\n                \n                    \n                <span style=\"animation: pulse-key942343367 3s linear infinite;\" class=\"et-pb-icon et-pb-font-icon dipi-hotspot-icon\">\n                    \uf140\n                <\/span>\n                    <style>@keyframes pulse-key942343367 {\n            0% {box-shadow: 0 0 0 0 rgba(, , , .3), 0 0 0 0 rgba(, , , .3);}\n            33% {box-shadow: 0 0 0 15px rgba(, , , 0), 0 0 0 0 rgba(, , , .5);}\n            66% {box-shadow: 0 0 0 10px rgba(, , , 0), 0 0 0 10px rgba(, , , 0);}\n            100% {box-shadow: 0 0 0 0 rgba(, , , 0), 0 0 0 15px rgba(, , , 0);}\n            }<\/style>\n                    \n                \n            <\/div>\n            <\/div><\/div>\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"et_pb_row_3 et_pb_row et-vb-row--no-module et_block_row\"><div class=\"et_pb_column_3 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough\"><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":225829,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"dipi_cpt_category":[],"class_list":["post-225840","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lastabotn - Lysefjorden 365<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lysefjorden365.com\/no\/kulturarv\/lastabotn\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lastabotn - Lysefjorden 365\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lysefjorden365.com\/no\/kulturarv\/lastabotn\/\" \/>\n<meta property=\"og:site_name\" content=\"Lysefjorden 365\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Lysefjorden365\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T13:37:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Ansl. lesetid\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/cultural-heritage\\\/lastabotn\\\/\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/cultural-heritage\\\/lastabotn\\\/\",\"name\":\"Lastabotn - Lysefjorden 365\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#website\"},\"datePublished\":\"2023-03-13T09:59:36+00:00\",\"dateModified\":\"2026-06-15T13:37:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/cultural-heritage\\\/lastabotn\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lysefjorden365.com\\\/cultural-heritage\\\/lastabotn\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/cultural-heritage\\\/lastabotn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/lysefjorden365.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultural heritage\",\"item\":\"https:\\\/\\\/lysefjorden365.com\\\/cultural-heritage\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lastabotn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#website\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/\",\"name\":\"Lysefjorden 365\",\"description\":\"quite simply a remarkable place\",\"publisher\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lysefjorden365.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#organization\",\"name\":\"Lysefjorden 365\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lysefjorden-365-logo-round.svg\",\"contentUrl\":\"https:\\\/\\\/lysefjorden365.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lysefjorden-365-logo-round.svg\",\"width\":1,\"height\":1,\"caption\":\"Lysefjorden 365\"},\"image\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Lysefjorden365\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lastabotn - Lysefjorden 365","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lysefjorden365.com\/no\/kulturarv\/lastabotn\/","og_locale":"nb_NO","og_type":"article","og_title":"Lastabotn - Lysefjorden 365","og_url":"https:\/\/lysefjorden365.com\/no\/kulturarv\/lastabotn\/","og_site_name":"Lysefjorden 365","article_publisher":"https:\/\/www.facebook.com\/Lysefjorden365\/","article_modified_time":"2026-06-15T13:37:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Ansl. lesetid":"6 minutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lysefjorden365.com\/cultural-heritage\/lastabotn\/","url":"https:\/\/lysefjorden365.com\/cultural-heritage\/lastabotn\/","name":"Lastabotn - Lysefjorden 365","isPartOf":{"@id":"https:\/\/lysefjorden365.com\/#website"},"datePublished":"2023-03-13T09:59:36+00:00","dateModified":"2026-06-15T13:37:49+00:00","breadcrumb":{"@id":"https:\/\/lysefjorden365.com\/cultural-heritage\/lastabotn\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lysefjorden365.com\/cultural-heritage\/lastabotn\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lysefjorden365.com\/cultural-heritage\/lastabotn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/lysefjorden365.com\/"},{"@type":"ListItem","position":2,"name":"Cultural heritage","item":"https:\/\/lysefjorden365.com\/cultural-heritage\/"},{"@type":"ListItem","position":3,"name":"Lastabotn"}]},{"@type":"WebSite","@id":"https:\/\/lysefjorden365.com\/#website","url":"https:\/\/lysefjorden365.com\/","name":"Lysefjorden 365","description":"rett og slett et bemerkelsesverdig sted","publisher":{"@id":"https:\/\/lysefjorden365.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lysefjorden365.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"},{"@type":"Organization","@id":"https:\/\/lysefjorden365.com\/#organization","name":"Lysefjorden 365","url":"https:\/\/lysefjorden365.com\/","logo":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/lysefjorden365.com\/#\/schema\/logo\/image\/","url":"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2019\/04\/lysefjorden-365-logo-round.svg","contentUrl":"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2019\/04\/lysefjorden-365-logo-round.svg","width":1,"height":1,"caption":"Lysefjorden 365"},"image":{"@id":"https:\/\/lysefjorden365.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Lysefjorden365\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:36:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"dipi_cpt_category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/lysefjorden365.com\/no\/wp-json\/wp\/v2\/pages\/225840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lysefjorden365.com\/no\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lysefjorden365.com\/no\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lysefjorden365.com\/no\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lysefjorden365.com\/no\/wp-json\/wp\/v2\/comments?post=225840"}],"version-history":[{"count":2,"href":"https:\/\/lysefjorden365.com\/no\/wp-json\/wp\/v2\/pages\/225840\/revisions"}],"predecessor-version":[{"id":237386,"href":"https:\/\/lysefjorden365.com\/no\/wp-json\/wp\/v2\/pages\/225840\/revisions\/237386"}],"up":[{"embeddable":true,"href":"https:\/\/lysefjorden365.com\/no\/wp-json\/wp\/v2\/pages\/225829"}],"wp:attachment":[{"href":"https:\/\/lysefjorden365.com\/no\/wp-json\/wp\/v2\/media?parent=225840"}],"wp:term":[{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/lysefjorden365.com\/no\/wp-json\/wp\/v2\/dipi_cpt_category?post=225840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}