{"id":223780,"date":"2022-08-03T09:27:39","date_gmt":"2022-08-03T07:27:39","guid":{"rendered":"https:\/\/lysefjorden365.wpenginepowered.com\/lysefjordruta\/strekning-3-jorpeland-ardal\/"},"modified":"2026-06-15T15:37:19","modified_gmt":"2026-06-15T13:37:19","slug":"jorpeland-ardal","status":"publish","type":"page","link":"https:\/\/lysefjorden365.com\/es\/lysefjordruta\/jorpeland-ardal\/","title":{"rendered":"Secuencia 3: J\u00f8rpeland \u2013 \u00c5rdal"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section section_has_divider et_pb_bottom_divider\"><div class=\"et_pb_row_0 et_pb_row et_pb_row_1-4_1-2_1-4 et_pb_equal_columns et_block_row et_block_row_1-4_1-2_1-4\"><div class=\"et_pb_column_0 et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_image_0 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/755-30-cm.png\" width=\"851\" height=\"851\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/755-30-cm.png 851w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/755-30-cm-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 851px, 100vw\" class=\"wp-image-223298\" title=\"755 30 cent\u00edmetros\" \/><\/span><\/div><\/div><div class=\"et_pb_column_1 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h1><span style=\"color: #ffffff;\">Etapa 3:<\/span><br \/><span style=\"color: #ffffff;\">J\u00f8rpeland \u2013 \u00c5rdal<\/span><\/h1>\n<\/div><\/div><\/div><div class=\"et_pb_column_2 et_pb_column et_pb_column_1_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_image_1 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/lysefjorden-365-symbol-sirkel-hvit.png\" width=\"350\" height=\"350\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/lysefjorden-365-symbol-sirkel-hvit.png 350w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/lysefjorden-365-symbol-sirkel-hvit-150x150.png 150w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/lysefjorden-365-symbol-sirkel-hvit-300x300.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" class=\"wp-image-223431\" title=\"lysefjorden-365-s\u00edmbolo-sirkel-hvit\" \/><\/span><\/div><\/div><\/div><div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div><div class=\"et_pb_section_1 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_1 et_pb_row et_pb_equal_columns et_block_row\"><div class=\"et_pb_column_3 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_d4_element dica_divi_carousel dica_divi_carousel_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dica-container  desktop_middle-inside tablet_middle-inside mobile_middle-inside arrow-on-hover\" data-props='{\"desktop\":\"1\",\"tablet\":\"1\",\"mobile\":\"1\",\"speed\":\"500\",\"arrow\":\"on\",\"dots\":\"off\",\"autoplay\":\"off\",\"autoSpeed\":\"1000\",\"loop\":\"on\",\"item_spacing\":\"30\",\"center_mode\":\"on\",\"slider_effec\":\"1\",\"cover_rotate\":\"50\",\"pause_onhover\":\"off\",\"multislide\":\"off\",\"cfshadow\":\"on\",\"order\":\"0\",\"lazyload\":\"off\",\"lazybefore\":\"off\",\"scroller_effect\":\"off\",\"autowidth\":\"off\",\"item_spacing_tablet\":\"30\",\"item_spacing_phone\":\"30\",\"scroller_speed\":\"4000\",\"hashNavigation\":\"off\",\"simulatetouch\":\"off\",\"allowtouchmove\":\"off\",\"slide_row\":\"1\",\"slide_row_tablet\":\"1\",\"slide_row_phone\":\"1\",\"keyboard\":\"off\",\"mousewheel\":\"off\",\"autoplay_viewport\":\"\"}'>\n\t\t\t\t\t\t\t \t<div class=\"swiper-container\" >\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-wrapper\"><div class=\"et_pb_module et_d4_element dica_divi_carouselitem dica_divi_carouselitem_0  et_pb_css_mix_blend_mode\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t <div class=\"dica-item empty-content image_top\"   data-hash=\"dica_divi_carouselitem_0\">\n\t\t\t\t\t\t\t\t\t<div class=\"dica-image-container\"><span class=\"image\"><img decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/Jorpeland-\u00c5rdal_02.jpg\" srcset=\"\" alt=\"\" class=\"dica-item-image\" width=\"f\" height=\"u\"\/><\/span><\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dica_divi_carouselitem dica_divi_carouselitem_1  et_pb_css_mix_blend_mode\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t <div class=\"dica-item empty-content image_top\"   data-hash=\"dica_divi_carouselitem_1\">\n\t\t\t\t\t\t\t\t\t<div class=\"dica-image-container\"><span class=\"image\"><img decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/Jorpeland-\u00c5rdal_03.jpg\" srcset=\"\" alt=\"\" class=\"dica-item-image\" width=\"f\" height=\"u\"\/><\/span><\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dica_divi_carouselitem dica_divi_carouselitem_2  et_pb_css_mix_blend_mode\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t <div class=\"dica-item empty-content image_top\"   data-hash=\"dica_divi_carouselitem_2\">\n\t\t\t\t\t\t\t\t\t<div class=\"dica-image-container\"><span class=\"image\"><img decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/Jorpeland-A\u030ardal_01.jpg\" srcset=\"\" alt=\"\" class=\"dica-item-image\" width=\"f\" height=\"u\"\/><\/span><\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dica_divi_carouselitem dica_divi_carouselitem_3  et_pb_css_mix_blend_mode\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t <div class=\"dica-item empty-content image_top\"   data-hash=\"dica_divi_carouselitem_3\">\n\t\t\t\t\t\t\t\t\t<div class=\"dica-image-container\"><span class=\"image\"><img decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/Jorpeland-A\u030ardal-04.jpg\" srcset=\"\" alt=\"\" class=\"dica-item-image\" width=\"f\" height=\"u\"\/><\/span><\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t\t<div class=\"swiper-buttton-container\"><div class=\"swiper-button-prev dica-prev-btn-0\" data-icon=\"4\"><\/div><div class=\"swiper-button-next dica-next-btn-0\" data-icon=\"5\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div><div class=\"et_pb_column_4 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><span>Desde J\u00f8rpeland, disfrute de unos kil\u00f3metros suaves a lo largo del fiordo, con amplias vistas de la cuenca de Ryfylke. Se divisa Rennes\u00f8y y se vislumbran otras islas e islotes de Ryfylke, as\u00ed como Stavanger a lo lejos. Merece la pena detenerse en el pueblo de Tau, conocido por su hermoso M\u00f8llepark. Desde aqu\u00ed, la ruta gira al este, pasando por el lago Bj\u00f8rheimsvatnet. A ambos lados del lago Tysdalsvatnet, escarpadas laderas se elevan cientos de metros sobre el agua. Aqu\u00ed se puede circular en bicicleta por la antigua carretera, sin tr\u00e1fico, atravesando la naturaleza salvaje. Los \u00faltimos kil\u00f3metros hacia \u00c5rdal deben recorrerse por la carretera nacional 13, sin carril bici. La carretera que atraviesa M\u00e5landsdalen pasa por un collado, por lo que puede haber mucho tr\u00e1fico y camiones.<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_2 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_2 et_pb_row et_pb_row_1-4_1-4_1-2 et_block_row et_block_row_1-4_1-4_1-2\"><div class=\"et_pb_column_5 et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_blurb_0 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Dificultad<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_1 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf111<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Moderado<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_2 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Esta etapa se recomienda para<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_3 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf84a<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">bicicletas de carretera\/turismo<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_4 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf5e7<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">bicicletas el\u00e9ctricas<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_5 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf206<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">bicicletas normales<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_6 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf0c0<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">familias (J\u00f8rpeland-Tysdalsvatnet)<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_7 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Estaci\u00f3n<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_8 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf073<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Todo el a\u00f1o<\/h4><\/div><\/div><\/div><\/div><div class=\"et_pb_column_6 et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_blurb_9 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Distancia<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_10 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf4d7<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">34 kil\u00f3metros<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_11 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Tr\u00e1fico<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_12 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf1b9<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">21 kil\u00f3metros<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_13 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf1b9<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">2 kil\u00f3metros<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_14 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf1b9<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">11 kil\u00f3metros<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_15 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Ganancia de elevaci\u00f3n total<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_16 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf161<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">300 metros (AB)<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_17 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf161<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">200 metros (BA)<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_18 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><a href=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/03_Jorpeland-A\u030ardal.gpx\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\uf124<\/span><\/span><\/a><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\"><a href=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/03_Jorpeland-A\u030ardal.gpx\">Archivo GPX<\/a><\/h4><\/div><\/div><\/div><\/div><div class=\"et_pb_column_7 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_code_0 et_pb_code et_pb_module\"><div class=\"et_pb_code_inner\"><iframe src=\"https:\/\/www.google.com\/maps\/d\/u\/1\/embed?mid=1i5NATtOUvCwvV8hcs_0Wof7kZG5AhUc&ehbc=2E312F\" width=\"100%\" height=\"465\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\"><\/iframe><\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_3 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_3 et_pb_row et_pb_gutters3 et_block_row\"><div class=\"et_pb_column_8 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h5>Informaci\u00f3n pr\u00e1ctica<\/h5>\n<\/div><\/div><div class=\"et_pb_divider_0 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>La antigua carretera que pasa por Tysdalsvatnet est\u00e1 cerrada de noviembre a abril debido al riesgo de nieve y desprendimientos de rocas.<\/p>\n<p>El tramo de carretera de Tysdalsvatnet a \u00c5rdal es muy transitado y no dispone de carril bici. No se recomienda ir en bicicleta con ni\u00f1os.<\/p>\n<p>La ruta ciclista se desv\u00eda hacia Songesand 5 km antes de \u00c5rdal.<\/p>\n<p><strong>Tiendas de deportes y bicicletas<\/strong><\/p>\n<ul>\n<li><strong><a href=\"https:\/\/goo.gl\/maps\/YVFGWE6pbz2Duyxj8\" target=\"_blank\" rel=\"noopener\">Deporte 1 J\u00f8rpeland<\/a><\/strong><\/li>\n<\/ul>\n<p><strong>Alquiler de bicicletas<\/strong><\/p>\n<ul>\n<li style=\"text-align: left;\"><strong><a href=\"https:\/\/lysefjorden.com\/\">Explora el fiordo de Lyse<\/a><\/strong><\/li>\n<\/ul>\n<p><strong>Tiendas de comestibles<\/strong><strong style=\"font-size: 18px;\"><\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/goo.gl\/maps\/nNZGbkevUjQGmuRK8\" target=\"_blank\" rel=\"noopener\"><strong>REMA 1000 J\u00f8rpeland<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/CXVFawFQ3ow5H1xV8\" target=\"_blank\" rel=\"noopener\"><strong>SPAR J\u00f8rpeland<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/gy8KaaXin6HnfDXTA\" target=\"_blank\" rel=\"noopener\"><strong>EXTRA J\u00f8rpeland<\/strong><\/a><\/li>\n<li><strong><a href=\"https:\/\/goo.gl\/maps\/i1DRfQPp9b9jiY969\" target=\"_blank\" rel=\"noopener\">EXTRA R\u00e5dhusgaten J\u00f8rpeland<\/a><\/strong><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/HDMvw4CVG4gyEmiY7\" target=\"_blank\" rel=\"noopener\"><strong>KIWI J\u00f8rpeland<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/toSi4hyoNRv9wfGK6\" target=\"_blank\" rel=\"noopener\"><strong>EXTRA Prestamarka<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/sPVEZuaPVDyDm1m28\" target=\"_blank\" rel=\"noopener\"><strong>Tau EXTRA<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/r2iiaznXFMJhAjei7\" target=\"_blank\" rel=\"noopener\"><strong>KIWI Tau<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/G27rfihp75noxbRx9\" target=\"_blank\" rel=\"noopener\"><strong>REMA 1000 Tau<\/strong><\/a><\/li>\n<li><strong><a href=\"https:\/\/goo.gl\/maps\/qjixH4dxeg4CEie78\" target=\"_blank\" rel=\"noopener\">Premio Coop \u00c5rdal<\/a><\/strong><strong><\/strong><\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"et_pb_column_9 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h5>Ver y hacer<\/h5>\n<\/div><\/div><div class=\"et_pb_divider_1 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><ul>\n<li><a href=\"https:\/\/preikestolen365.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Caminata por Preikestolen<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/V2UZWED3GAWgH8UF9\" target=\"_blank\" rel=\"noopener\"><strong>Club de golf Preikestolen<\/strong><\/a><strong><\/strong><\/li>\n<li><a href=\"https:\/\/ryfylkebyen.no\/en\/\" target=\"_blank\" rel=\"noopener\"><strong>Ryfylkebyen J\u00f8rpeland<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/DeQVzVH5y81y6v6a8\" target=\"_blank\" rel=\"noopener\"><strong>Lysefjorden Sjokolade<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/R2kDW5u4Ham1tSTp6\" target=\"_blank\" rel=\"noopener\"><strong>J\u00f8rpelandsholmen<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/9GWm4gNMFj6BNvbr6\" target=\"_blank\" rel=\"noopener\"><strong>J\u00f8rpelandsfossen<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/Wsr7o8nhS6MB1bxb7\" target=\"_blank\" rel=\"noopener\"><strong>Dalen Stisenter<\/strong><\/a><br \/><strong><\/strong><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/PuUhhFEcKMPVTqSA7\" target=\"_blank\" rel=\"noopener\"><strong>Grabados rupestres en Solbakk<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/3EHZKk54n75o2ARq5\" target=\"_blank\" rel=\"noopener\"><strong>Parque M\u00f8lle<\/strong><\/a><br \/><strong><\/strong><\/li>\n<li><a href=\"https:\/\/www.fjordnorway.com\/no\/se-og-gjore\/minnesmerket-i-holtaheia-strand\" target=\"_blank\" rel=\"noopener\"><strong>Caminata por Holtaheia<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/www.fjordnorway.com\/no\/se-og-gjore\/reinaknuten\" target=\"_blank\" rel=\"noopener\"><strong>Caminata por Reinaknuten<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/ASGghmDCZc2X7qYm9\" target=\"_blank\" rel=\"noopener\"><strong>Eventyrskogen<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/tjPUEhPui2TVuuqp9\" target=\"_blank\" rel=\"noopener\"><strong>Iglesia de \u00c5rdal Gamle<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/www.fjordnorway.com\/no\/se-og-gjore\/hiafossen\" target=\"_blank\" rel=\"noopener\"><strong>Hiafossen<\/strong><\/a><strong><\/strong><\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"et_pb_column_10 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h5>Dormir y comer<\/h5>\n<\/div><\/div><div class=\"et_pb_divider_2 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><strong>J\u00f8rpeland<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/goo.gl\/maps\/RZX95zvqoWCt2awZ9\" target=\"_blank\" rel=\"noopener\"><strong>Marih\u00f8nehuset<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/www.preikestolencamping.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Camping Preikestolen<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/preikestolenbasecamp.com\/en\/\" target=\"_blank\" rel=\"noopener\"><strong>Campamento base de Preikestolen<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/verkshotellet.no\/\" target=\"_blank\" rel=\"noopener\"><strong>Verkshotellet<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/DaQS47BegSbrr4QLA\" target=\"_blank\" rel=\"noopener\"><strong>Ryfylke Bakeri og Konditori<\/strong><\/a><\/li>\n<\/ul>\n<p><strong>Tau<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/lillandhotell.no\/\" target=\"_blank\" rel=\"noopener\"><strong>Hotel Lilland Bryggeri<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/g.page\/meatandeattau?share\" target=\"_blank\" rel=\"noopener\"><strong>Carne y comer<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/BGofGHCzZ8urUxwK7\" target=\"_blank\" rel=\"noopener\"><strong>Caf\u00e9 Marthel<\/strong><\/a><\/li>\n<\/ul>\n<p><strong>Bj\u00f8rheimsbygd - \u00c5rdal<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/goo.gl\/maps\/X49JqSo7s5PytbTc6\" target=\"_blank\" rel=\"noopener\"><strong>Vaulali Leirsted<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/92sYMZD1Cf81mTV39\" target=\"_blank\" rel=\"noopener\"><strong>Camping Wathne<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/FeqiW5EvVpU1AULWA\" target=\"_blank\" rel=\"noopener\"><strong>Camping Tysdal<\/strong><\/a><\/li>\n<\/ul>\n<p><strong>\u00c5rdal<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/goo.gl\/maps\/XGeTaq3EFN7mLZuu8\" target=\"_blank\" rel=\"noopener\"><strong>Holanda Gard<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/goo.gl\/maps\/rtKd1X2oZLZ1Z7Hk7\" target=\"_blank\" rel=\"noopener\"><strong>Restaurante Gea<\/strong><\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_4 et_pb_row et_block_row\"><div class=\"et_pb_column_11 et_pb_column et_pb_column_2_3 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_image_2 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/Lysefjordruta_logo.png\" width=\"1920\" height=\"529\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/Lysefjordruta_logo.png 1920w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/Lysefjordruta_logo-1280x353.png 1280w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/Lysefjordruta_logo-980x270.png 980w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2022\/08\/Lysefjordruta_logo-480x132.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1920px, 100vw\" class=\"wp-image-223324\" title=\"Logotipo de Lysefjordruta\" \/><\/span><\/div><\/div><div class=\"et_pb_column_12 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_menu_0 et_pb_menu et_pb_menu--without-logo et_pb_menu--style-left_aligned et_dropdown_animation_fade et_pb_bg_layout_light et_pb_text_align_right-tablet et_pb_text_align_right-phone et_pb_module et_flex_module etappeDetalj\"><div class=\"et_pb_menu_inner_container et_flex_module\"><div class=\"et_pb_menu__wrap\"><div class=\"et_pb_menu__menu\"><nav class=\"et-menu-nav\"><ul id=\"menu-lysefjordruta-en\" class=\"et-menu nav downwards\"><li id=\"menu-item-223807\" class=\"et_pb_menu_page_id-223776 menu-item menu-item-type-post_type menu-item-object-page menu-item-223807\"><a href=\"https:\/\/lysefjorden365.com\/es\/lysefjordruta\/sandnes-oanes-forsand\/\">Ruta 1: Sandnes \u2013 Oanes\/Forsand<\/a><\/li>\n<li id=\"menu-item-223806\" class=\"et_pb_menu_page_id-223778 menu-item menu-item-type-post_type menu-item-object-page menu-item-223806\"><a href=\"https:\/\/lysefjorden365.com\/es\/lysefjordruta\/oanes-forsand-jorpeland\/\">Ruta 2: Oanes\/Forsand \u2013 J\u00f8rpeland<\/a><\/li>\n<li id=\"menu-item-223805\" class=\"et_pb_menu_page_id-223780 menu-item menu-item-type-post_type menu-item-object-page menu-item-223805\"><a href=\"https:\/\/lysefjorden365.com\/es\/lysefjordruta\/jorpeland-ardal\/\">Secuencia 3: J\u00f8rpeland \u2013 \u00c5rdal<\/a><\/li>\n<li id=\"menu-item-223804\" class=\"et_pb_menu_page_id-223782 menu-item menu-item-type-post_type menu-item-object-page menu-item-223804\"><a href=\"https:\/\/lysefjorden365.com\/es\/lysefjordruta\/ardal-songesand-lysebotn\/\">Secuencia 4: \u00c5rdal \u2013 Songesand\/Lysebotn<\/a><\/li>\n<li id=\"menu-item-223803\" class=\"et_pb_menu_page_id-223784 menu-item menu-item-type-post_type menu-item-object-page menu-item-223803\"><a href=\"https:\/\/lysefjorden365.com\/es\/lysefjordruta\/songesand-lysebotn-sirdal\/\">Strekning 5: Songesand\/Lysebotn \u2013 Sirdal<\/a><\/li>\n<li id=\"menu-item-223802\" class=\"et_pb_menu_page_id-223786 menu-item menu-item-type-post_type menu-item-object-page menu-item-223802\"><a href=\"https:\/\/lysefjorden365.com\/es\/lysefjordruta\/sirdal-byrkjedal\/\">Secuencia 6: Sirdal \u2013 Byrkjedal<\/a><\/li>\n<li id=\"menu-item-223801\" class=\"et_pb_menu_page_id-223788 menu-item menu-item-type-post_type menu-item-object-page menu-item-223801\"><a href=\"https:\/\/lysefjorden365.com\/es\/lysefjordruta\/byrkjedal-sandnes\/\">Secuencia 7: Byrkjedal \u2013 Sandnes<\/a><\/li>\n<\/ul><\/nav><\/div><div class=\"et_mobile_nav_menu\"><div class=\"mobile_nav closed\"><span class=\"mobile_menu_bar\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_4 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_5 et_pb_row et_block_row\"><div class=\"et_pb_column_13 et_pb_column et_pb_column_3_5 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h3>Gu\u00eda tur\u00edstica del fiordo de Lysefjord<\/h3>\n<\/div><\/div><div class=\"et_pb_text_9 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p style=\"text-align: left;\">Mientras experimenta este majestuoso paisaje, recuerde que sus acciones tienen el poder de proteger y celebrar nuestro destino \u00fanico para todos los que siguen sus pasos.<\/p>\n<\/div><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"https:\/\/lysefjorden365.com\/es\/lysefjord-visitor-guide\/\" data-icon=\"$\">Vea nuestra gu\u00eda<\/a><\/div><\/div><div class=\"et_pb_column_14 et_pb_column et_pb_column_2_5 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_blurb_19 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module preset--module--divi-blurb--bca38d7f-b726-4c6c-8de5-b47afa5b3268\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/respect-nature.webp\" width=\"1461\" height=\"1464\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/respect-nature.webp 1461w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/respect-nature-1280x1283.webp 1280w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/respect-nature-980x982.webp 980w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/respect-nature-480x481.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1461px, 100vw\" class=\"wp-image-236175\" alt=\"Fjellvann og natur i Lysefjorden, Stavanger, Norge, con spektakul\u00e6r utsikt y unike geografiske landformer. Opplev den vakre fiorden y og oppdag roen i det natural landskapet.\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Respetar la naturaleza<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_20 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module preset--module--divi-blurb--bca38d7f-b726-4c6c-8de5-b47afa5b3268\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/be-part-of-the-community.png.webp\" width=\"1458\" height=\"1461\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/be-part-of-the-community.png.webp 1458w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/be-part-of-the-community.png-1280x1283.webp 1280w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/be-part-of-the-community.png-980x982.webp 980w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/be-part-of-the-community.png-480x481.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1458px, 100vw\" class=\"wp-image-236158\" alt=\"Ex\u00f3tico recorrido por Lysefjorden con fjellandskap y seilb\u00e5ter i solnedgang, perfecto para fiorturistas y naturopplevelser en S\u00f8r-Norge.\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Sea parte de la comunidad local<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_21 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module preset--module--divi-blurb--bca38d7f-b726-4c6c-8de5-b47afa5b3268\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/be-safe.png.webp\" width=\"1462\" height=\"1462\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/be-safe.png.webp 1462w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/be-safe.png-1280x1280.webp 1280w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/be-safe.png-980x980.webp 980w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/be-safe.png-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1462px, 100vw\" class=\"wp-image-236160\" alt=\"Sikkerhetsikon med skjold y V de beskyttelse, s\u00edmbolo de trygghet y sikkerhet.\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Mantenerse seguro<\/h4><\/div><\/div><\/div><div class=\"et_pb_blurb_22 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module preset--module--divi-blurb--bca38d7f-b726-4c6c-8de5-b47afa5b3268\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/choose-sustainability.webp\" width=\"1458\" height=\"1461\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/choose-sustainability.webp 1458w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/choose-sustainability-1280x1283.webp 1280w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/choose-sustainability-980x982.webp 980w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2026\/01\/choose-sustainability-480x481.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1458px, 100vw\" class=\"wp-image-236178\" alt=\"Resirkuleringssymbol para milj\u00f8vennlig avfallsh\u00e5ndtering, b\u00e6rekraft og resirkulering.\" \/><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Elija alternativas sostenibles<\/h4><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":223763,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"dipi_cpt_category":[],"class_list":["post-223780","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Strekning 3: J\u00f8rpeland \u2013 \u00c5rdal - Lysefjorden 365<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lysefjorden365.com\/es\/ruta-del-fiordo-de-lysefjord\/jorpeland-ardal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Strekning 3: J\u00f8rpeland \u2013 \u00c5rdal - Lysefjorden 365\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lysefjorden365.com\/es\/ruta-del-fiordo-de-lysefjord\/jorpeland-ardal\/\" \/>\n<meta property=\"og:site_name\" content=\"Lysefjorden 365\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Lysefjorden365\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T13:37:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/lysefjordruta\\\/jorpeland-ardal\\\/\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/lysefjordruta\\\/jorpeland-ardal\\\/\",\"name\":\"Strekning 3: J\u00f8rpeland \u2013 \u00c5rdal - Lysefjorden 365\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#website\"},\"datePublished\":\"2022-08-03T07:27:39+00:00\",\"dateModified\":\"2026-06-15T13:37:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/lysefjordruta\\\/jorpeland-ardal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lysefjorden365.com\\\/lysefjordruta\\\/jorpeland-ardal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/lysefjordruta\\\/jorpeland-ardal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/lysefjorden365.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lysefjordruta\",\"item\":\"https:\\\/\\\/lysefjorden365.com\\\/lysefjordruta\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Strekning 3: J\u00f8rpeland \u2013 \u00c5rdal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#website\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/\",\"name\":\"Lysefjorden 365\",\"description\":\"quite simply a remarkable place\",\"publisher\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lysefjorden365.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#organization\",\"name\":\"Lysefjorden 365\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lysefjorden-365-logo-round.svg\",\"contentUrl\":\"https:\\\/\\\/lysefjorden365.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lysefjorden-365-logo-round.svg\",\"width\":1,\"height\":1,\"caption\":\"Lysefjorden 365\"},\"image\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Lysefjorden365\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ruta 3: J\u00f8rpeland \u2013 \u00c5rdal - Lysefjorden 365","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lysefjorden365.com\/es\/ruta-del-fiordo-de-lysefjord\/jorpeland-ardal\/","og_locale":"es_ES","og_type":"article","og_title":"Strekning 3: J\u00f8rpeland \u2013 \u00c5rdal - Lysefjorden 365","og_url":"https:\/\/lysefjorden365.com\/es\/ruta-del-fiordo-de-lysefjord\/jorpeland-ardal\/","og_site_name":"Lysefjorden 365","article_publisher":"https:\/\/www.facebook.com\/Lysefjorden365\/","article_modified_time":"2026-06-15T13:37:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lysefjorden365.com\/lysefjordruta\/jorpeland-ardal\/","url":"https:\/\/lysefjorden365.com\/lysefjordruta\/jorpeland-ardal\/","name":"Ruta 3: J\u00f8rpeland \u2013 \u00c5rdal - Lysefjorden 365","isPartOf":{"@id":"https:\/\/lysefjorden365.com\/#website"},"datePublished":"2022-08-03T07:27:39+00:00","dateModified":"2026-06-15T13:37:19+00:00","breadcrumb":{"@id":"https:\/\/lysefjorden365.com\/lysefjordruta\/jorpeland-ardal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lysefjorden365.com\/lysefjordruta\/jorpeland-ardal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lysefjorden365.com\/lysefjordruta\/jorpeland-ardal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/lysefjorden365.com\/"},{"@type":"ListItem","position":2,"name":"Lysefjordruta","item":"https:\/\/lysefjorden365.com\/lysefjordruta\/"},{"@type":"ListItem","position":3,"name":"Strekning 3: J\u00f8rpeland \u2013 \u00c5rdal"}]},{"@type":"WebSite","@id":"https:\/\/lysefjorden365.com\/#website","url":"https:\/\/lysefjorden365.com\/","name":"Lysefjord 365","description":"Sencillamente un lugar extraordinario","publisher":{"@id":"https:\/\/lysefjorden365.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lysefjorden365.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lysefjorden365.com\/#organization","name":"Lysefjord 365","url":"https:\/\/lysefjorden365.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lysefjorden365.com\/#\/schema\/logo\/image\/","url":"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2019\/04\/lysefjorden-365-logo-round.svg","contentUrl":"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2019\/04\/lysefjorden-365-logo-round.svg","width":1,"height":1,"caption":"Lysefjorden 365"},"image":{"@id":"https:\/\/lysefjorden365.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Lysefjorden365\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 04:58:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"dipi_cpt_category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/lysefjorden365.com\/es\/wp-json\/wp\/v2\/pages\/223780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lysefjorden365.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lysefjorden365.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lysefjorden365.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lysefjorden365.com\/es\/wp-json\/wp\/v2\/comments?post=223780"}],"version-history":[{"count":2,"href":"https:\/\/lysefjorden365.com\/es\/wp-json\/wp\/v2\/pages\/223780\/revisions"}],"predecessor-version":[{"id":237370,"href":"https:\/\/lysefjorden365.com\/es\/wp-json\/wp\/v2\/pages\/223780\/revisions\/237370"}],"up":[{"embeddable":true,"href":"https:\/\/lysefjorden365.com\/es\/wp-json\/wp\/v2\/pages\/223763"}],"wp:attachment":[{"href":"https:\/\/lysefjorden365.com\/es\/wp-json\/wp\/v2\/media?parent=223780"}],"wp:term":[{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/lysefjorden365.com\/es\/wp-json\/wp\/v2\/dipi_cpt_category?post=223780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}