{"id":218901,"date":"2021-04-15T10:42:12","date_gmt":"2021-04-15T08:42:12","guid":{"rendered":"https:\/\/lysefjorden365.wpenginepowered.com\/i-naerheten\/listvisning\/"},"modified":"2026-06-15T15:35:40","modified_gmt":"2026-06-15T13:35:40","slug":"listenansicht","status":"publish","type":"page","link":"https:\/\/lysefjorden365.com\/de\/plan-your-stay-gammel\/listview\/","title":{"rendered":"Listenansicht"},"content":{"rendered":"\n<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_0 et_pb_row et_block_row\"><div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_code_0 et_pb_code et_pb_module\"><div class=\"et_pb_code_inner\"><style>\n.mapsvg-header .mapsvg-filters-wrap .mapsvg-data-form-view {\n  margin-left: -20px;\n}\n<\/style>\n\n<script type=\"text\/javascript\">\n\/\/ buttons for list view hidden as a default state, show based on url parameter \n\/\/ Parse the URL parameter\nfunction getParameterByName(name, url) {\n    if (!url) url = window.location.href;\n    name = name.replace(\/[\\[\\]]\/g, \"\\\\$&\");\n    var regex = new RegExp(\"[?&]\" + name + \"(=([^&#]*)|&|#|$)\"),\n        results = regex.exec(url);\n    if (!results) return null;\n    if (!results[2]) return '';\n    return decodeURIComponent(results[2].replace(\/\\+\/g, \" \"));\n}\n\n$(document).on('readystatechange', function() {\n    if (window.location.href == \"https:\/\/lysefjorden365.com\/plan-your-stay-gammel\/listview\/\") {\n        setTimeout(function() {\n          $(\".et_pb_code_2\").css(\"display\", \"block\");\n          $(\".mapsvg-filters-reset-container > .mapsvg-filters-reset\").click();\n        }, 1800);\n    }\n});\n\n\/\/ Give the parameter a variable name\nvar dynamicContent = getParameterByName('categories');\n  console.log(dynamicContent);\n  \n  $(document).ready(function() {\n    \n\t\t\/\/ Check if the URL parameter is Aktiviteter\n    \n    $(\".mapsvg-directory .mapsvg-directory-item\").delay(3000).css(\"display\", \"none\");\n    \n    let dirItemActivity = $(\".mapsvg-directory .mapsvg-directory-item .mapDetailCategories:contains('Activities')\");\n    \n\t\tif (dynamicContent == 'Activities' && dirItemActivity ) {\n\t\t\t$('#ListviewActivities').show();\n      let dirItem = $(\".mapsvg-directory .mapsvg-directory-item\").delay(5000).css(\"display\", \"block\");\n        console.log(\"It shows activities...\");\n\t\t} \n\t\t\/\/ Check if the URL parameter is Transport\n\t\telse if (dynamicContent == 'Transport') {\n\t\t\t$('#ListviewTransport').show();\n\t\t} \n\t\t\/\/ Check if the URL parameter is Overnatting\n\t\telse if (dynamicContent == 'Accommodation') {\n\t\t\t$('#ListviewAccommodation').show();\n\t\t} \n    \t\t\/\/ Check if the URL parameter is Servering\n\t\telse if (dynamicContent == 'Food-and-Beverages') {\n\t\t\t$('#ListviewServing').show();\n\t\t}\n    \n\t\t\/\/ Check if the URL parmeter is empty or not defined, display default content\n\t\telse {\n\t\t\t$('#ListviewDefault').show();\n\t\t}\n    \n\t});\n  \n  \n  <\/script><\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_1 et_pb_section et_section_regular et_block_section listvisningSection\" id=\"ListviewDefault\"><div class=\"et_pb_row_1 et_pb_row et_block_row\"><div class=\"et_pb_column_1 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h1 style=\"text-align: center;\"><span>The surroundings around Lysefjorden<\/span><\/h1>\n<\/div><\/div><div class=\"et_pb_divider_0 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><\/div><\/div><div class=\"et_pb_row_2 et_pb_row et_block_row maplistviewButtonRow\"><div class=\"et_pb_column_2 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton\" href=\"\/map\/\" data-icon=\"\ue01f\">Show On Map<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Transport\">Transport<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_2_wrapper\"><a class=\"et_pb_button_2 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Food-and-Beverages\">F&amp;B<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_3_wrapper\"><a class=\"et_pb_button_3 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Accommodation\">Accommodation<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_4_wrapper\"><a class=\"et_pb_button_4 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Activities\">Activities<\/a><\/div><\/div><\/div><\/div><div class=\"et_pb_section_2 et_pb_section et_section_regular et_block_section listvisningSection\" id=\"ListviewActivities\"><div class=\"et_pb_row_3 et_pb_row et_block_row\"><div class=\"et_pb_column_3 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\"><span>The surroundings around Lysefjorden<\/span><\/h3>\n<h1 style=\"text-align: center;\">Activities<\/h1>\n<\/div><\/div><div class=\"et_pb_divider_1 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><span><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv.png\" width=\"275\" height=\"154\" alt=\"\" class=\"wp-image-228568 alignnone size-full\" style=\"float: left;\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv.png 1132w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-300x168.png 300w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-768x430.png 768w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-1024x574.png 1024w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-1080x605.png 1080w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-980x549.png 980w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-480x269.png 479w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>Tourism providers with a \"Travel Green\" badge are prioritized on our websites. This badge signifies that the provider holds at least one official environmental certification, such as Norwegian Ecotourism, The Swan, Eco-Lighthouse, ISO 14001, Green Key, or Blue Flag. The experiences highlighted with this badge adhere to stringent regulations and guidelines concerning the production and management of waste, energy use, transportation, subcontractor standards, and chemical usage. These initiatives exceed the requirements of Norwegian law, demonstrating a commitment to environmental responsibility.<\/span><\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_4 et_pb_row et_block_row maplistviewButtonRow\"><div class=\"et_pb_column_4 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_5_wrapper\"><a class=\"et_pb_button_5 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton\" href=\"\/map\/?categories=Activities\" data-icon=\"\ue01f\">Show on map<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_6_wrapper\"><a class=\"et_pb_button_6 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Transport\">Transport<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_7_wrapper\"><a class=\"et_pb_button_7 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Food-and-Beverages\">F&amp;B<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_8_wrapper\"><a class=\"et_pb_button_8 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Accommodation\">Accommodation<\/a><\/div><\/div><\/div><\/div><div class=\"et_pb_section_3 et_pb_section et_section_regular et_block_section listvisningSection\" id=\"ListviewTransport\"><div class=\"et_pb_row_5 et_pb_row et_block_row\"><div class=\"et_pb_column_5 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\"><span>The surroundings around Lysefjorden<\/span><\/h3>\n<h1 style=\"text-align: center;\">Transport<\/h1>\n<\/div><\/div><div class=\"et_pb_divider_2 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><span><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv.png\" width=\"275\" height=\"154\" alt=\"\" class=\"wp-image-228568 alignnone size-full\" style=\"float: left;\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv.png 1132w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-300x168.png 300w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-768x430.png 768w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-1024x574.png 1024w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-1080x605.png 1080w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-980x549.png 980w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-480x269.png 479w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>Tourism providers with a \"Travel Green\" badge are prioritized on our websites. This badge signifies that the provider holds at least one official environmental certification, such as Norwegian Ecotourism, The Swan, Eco-Lighthouse, ISO 14001, Green Key, or Blue Flag. The experiences highlighted with this badge adhere to stringent regulations and guidelines concerning the production and management of waste, energy use, transportation, subcontractor standards, and chemical usage. These initiatives exceed the requirements of Norwegian law, demonstrating a commitment to environmental responsibility.<\/span><\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_6 et_pb_row et_block_row maplistviewButtonRow\"><div class=\"et_pb_column_6 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_9_wrapper\"><a class=\"et_pb_button_9 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton\" href=\"\/map\/?categories=Transport\" data-icon=\"\ue01f\">Show on map<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_10_wrapper\"><a class=\"et_pb_button_10 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Activities\">Activities<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_11_wrapper\"><a class=\"et_pb_button_11 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Food-and-Beverages\">F&amp;B<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_12_wrapper\"><a class=\"et_pb_button_12 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Accommodation\">Accommodation<\/a><\/div><\/div><\/div><\/div><div class=\"et_pb_section_4 et_pb_section et_section_regular et_block_section listvisningSection\" id=\"ListviewServing\"><div class=\"et_pb_row_7 et_pb_row et_block_row\"><div class=\"et_pb_column_7 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\"><span>The surroundings around Lysefjorden<\/span><\/h3>\n<h1 style=\"text-align: center;\">F&amp;B<\/h1>\n<\/div><\/div><div class=\"et_pb_divider_3 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><span><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv.png\" width=\"275\" height=\"154\" alt=\"\" class=\"wp-image-228568 alignnone size-full\" style=\"float: left;\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv.png 1132w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-300x168.png 300w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-768x430.png 768w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-1024x574.png 1024w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-1080x605.png 1080w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-980x549.png 980w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-480x269.png 479w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>Tourism providers with a \"Travel Green\" badge are prioritized on our websites. This badge signifies that the provider holds at least one official environmental certification, such as Norwegian Ecotourism, The Swan, Eco-Lighthouse, ISO 14001, Green Key, or Blue Flag. The experiences highlighted with this badge adhere to stringent regulations and guidelines concerning the production and management of waste, energy use, transportation, subcontractor standards, and chemical usage. These initiatives exceed the requirements of Norwegian law, demonstrating a commitment to environmental responsibility.<\/span><\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_8 et_pb_row et_block_row maplistviewButtonRow\"><div class=\"et_pb_column_8 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_13_wrapper\"><a class=\"et_pb_button_13 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton\" href=\"\/map\/?categories=Food-and-Beverages\" data-icon=\"\ue01f\">Show on map<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_14_wrapper\"><a class=\"et_pb_button_14 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Transport\">Transport<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_15_wrapper\"><a class=\"et_pb_button_15 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Activities\">Activities<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_16_wrapper\"><a class=\"et_pb_button_16 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Accommodation\">Accommodation<\/a><\/div><\/div><\/div><\/div><div class=\"et_pb_section_5 et_pb_section et_section_regular et_block_section listvisningSection\" id=\"ListviewAccommodation\"><div class=\"et_pb_row_9 et_pb_row et_block_row\"><div class=\"et_pb_column_9 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\"><span>The surroundings around Lysefjorden<\/span><\/h3>\n<h1 style=\"text-align: center;\">Accommodation<\/h1>\n<\/div><\/div><div class=\"et_pb_divider_4 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><span><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv.png\" width=\"275\" height=\"154\" alt=\"\" class=\"wp-image-228568 alignnone size-full\" style=\"float: left;\" srcset=\"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv.png 1132w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-300x168.png 300w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-768x430.png 768w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-1024x574.png 1024w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-1080x605.png 1080w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-980x549.png 980w, https:\/\/lysefjorden365.com\/wp-content\/uploads\/2024\/02\/Reis-Gr\u251c\u00a9nt_Engelsk_Positiv-480x269.png 479w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>Tourism providers with a \"Travel Green\" badge are prioritized on our websites. This badge signifies that the provider holds at least one official environmental certification, such as Norwegian Ecotourism, The Swan, Eco-Lighthouse, ISO 14001, Green Key, or Blue Flag. The experiences highlighted with this badge adhere to stringent regulations and guidelines concerning the production and management of waste, energy use, transportation, subcontractor standards, and chemical usage. These initiatives exceed the requirements of Norwegian law, demonstrating a commitment to environmental responsibility.<\/span><\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_10 et_pb_row et_block_row maplistviewButtonRow\"><div class=\"et_pb_column_10 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_17_wrapper\"><a class=\"et_pb_button_17 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton\" href=\"\/map\/?categories=Accommodation\" data-icon=\"\ue01f\">Show on map<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_18_wrapper\"><a class=\"et_pb_button_18 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Transport\">Transport<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_19_wrapper\"><a class=\"et_pb_button_19 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Food-and-Beverages\">F&amp;B<\/a><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_20_wrapper\"><a class=\"et_pb_button_20 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module ListButton2\" href=\"\/plan-your-stay\/listview\/?categories=Activities\">Activities<\/a><\/div><\/div><\/div><\/div><div class=\"et_pb_section_6 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_11 et_pb_row et_block_row\"><div class=\"et_pb_column_11 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_code_1 et_pb_code et_pb_module\" id=\"mapDirectoryList\"><div class=\"et_pb_code_inner\"><!--  show directory #mapDirectoryList --><\/div><\/div><div class=\"et_pb_code_2 et_pb_code et_pb_module\"><div class=\"et_pb_code_inner\"><!--  hide map content - downloads map and directory to page -->\n<div id=\"mapsvg-219034\" data-id=\"219034\" class=\"mapsvg\" data-autoload=\"true\" data-load-db=\"true\" data-loading-text=\"Loading map...\" style=\"width: 100%; height: 0; padding-bottom: 65.89%\"><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":219265,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"dipi_cpt_category":[],"class_list":["post-218901","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>List view - Lysefjorden 365<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lysefjorden365.com\/de\/planen-sie-ihren-aufenthalt-in-gamel\/listenansicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"List view - Lysefjorden 365\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lysefjorden365.com\/de\/planen-sie-ihren-aufenthalt-in-gamel\/listenansicht\/\" \/>\n<meta property=\"og:site_name\" content=\"Lysefjorden 365\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Lysefjorden365\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T13:35:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/plan-your-stay-gammel\\\/listview\\\/\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/plan-your-stay-gammel\\\/listview\\\/\",\"name\":\"List view - Lysefjorden 365\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#website\"},\"datePublished\":\"2021-04-15T08:42:12+00:00\",\"dateModified\":\"2026-06-15T13:35:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/plan-your-stay-gammel\\\/listview\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lysefjorden365.com\\\/plan-your-stay-gammel\\\/listview\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/plan-your-stay-gammel\\\/listview\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/lysefjorden365.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan your stay (gammel)\",\"item\":\"https:\\\/\\\/lysefjorden365.com\\\/plan-your-stay-gammel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"List view\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#website\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/\",\"name\":\"Lysefjorden 365\",\"description\":\"quite simply a remarkable place\",\"publisher\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lysefjorden365.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#organization\",\"name\":\"Lysefjorden 365\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lysefjorden365.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lysefjorden-365-logo-round.svg\",\"contentUrl\":\"https:\\\/\\\/lysefjorden365.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lysefjorden-365-logo-round.svg\",\"width\":1,\"height\":1,\"caption\":\"Lysefjorden 365\"},\"image\":{\"@id\":\"https:\\\/\\\/lysefjorden365.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Lysefjorden365\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Listenansicht - Lysefjorden 365","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lysefjorden365.com\/de\/planen-sie-ihren-aufenthalt-in-gamel\/listenansicht\/","og_locale":"de_DE","og_type":"article","og_title":"List view - Lysefjorden 365","og_url":"https:\/\/lysefjorden365.com\/de\/planen-sie-ihren-aufenthalt-in-gamel\/listenansicht\/","og_site_name":"Lysefjorden 365","article_publisher":"https:\/\/www.facebook.com\/Lysefjorden365\/","article_modified_time":"2026-06-15T13:35:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lysefjorden365.com\/plan-your-stay-gammel\/listview\/","url":"https:\/\/lysefjorden365.com\/plan-your-stay-gammel\/listview\/","name":"Listenansicht - Lysefjorden 365","isPartOf":{"@id":"https:\/\/lysefjorden365.com\/#website"},"datePublished":"2021-04-15T08:42:12+00:00","dateModified":"2026-06-15T13:35:40+00:00","breadcrumb":{"@id":"https:\/\/lysefjorden365.com\/plan-your-stay-gammel\/listview\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lysefjorden365.com\/plan-your-stay-gammel\/listview\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lysefjorden365.com\/plan-your-stay-gammel\/listview\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/lysefjorden365.com\/"},{"@type":"ListItem","position":2,"name":"Plan your stay (gammel)","item":"https:\/\/lysefjorden365.com\/plan-your-stay-gammel\/"},{"@type":"ListItem","position":3,"name":"List view"}]},{"@type":"WebSite","@id":"https:\/\/lysefjorden365.com\/#website","url":"https:\/\/lysefjorden365.com\/","name":"Lysefjorden 365","description":"Einfach ein bemerkenswerter Ort","publisher":{"@id":"https:\/\/lysefjorden365.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lysefjorden365.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/lysefjorden365.com\/#organization","name":"Lysefjorden 365","url":"https:\/\/lysefjorden365.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/lysefjorden365.com\/#\/schema\/logo\/image\/","url":"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2019\/04\/lysefjorden-365-logo-round.svg","contentUrl":"https:\/\/lysefjorden365.com\/wp-content\/uploads\/2019\/04\/lysefjorden-365-logo-round.svg","width":1,"height":1,"caption":"Lysefjorden 365"},"image":{"@id":"https:\/\/lysefjorden365.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Lysefjorden365\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 14:07:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"dipi_cpt_category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/lysefjorden365.com\/de\/wp-json\/wp\/v2\/pages\/218901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lysefjorden365.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lysefjorden365.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lysefjorden365.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lysefjorden365.com\/de\/wp-json\/wp\/v2\/comments?post=218901"}],"version-history":[{"count":1,"href":"https:\/\/lysefjorden365.com\/de\/wp-json\/wp\/v2\/pages\/218901\/revisions"}],"predecessor-version":[{"id":237326,"href":"https:\/\/lysefjorden365.com\/de\/wp-json\/wp\/v2\/pages\/218901\/revisions\/237326"}],"up":[{"embeddable":true,"href":"https:\/\/lysefjorden365.com\/de\/wp-json\/wp\/v2\/pages\/219265"}],"wp:attachment":[{"href":"https:\/\/lysefjorden365.com\/de\/wp-json\/wp\/v2\/media?parent=218901"}],"wp:term":[{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/lysefjorden365.com\/de\/wp-json\/wp\/v2\/dipi_cpt_category?post=218901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}